{"id":37,"count":14,"description":"","link":"https:\/\/envoltaenergia.com\/es\/category\/solar\/","name":"Energia Solar","slug":"solar","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Energia Solar archivos - Envolta<\/title>\n<meta name=\"description\" content=\"\u2713\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Energia Solar archivos - Envolta\" \/>\n<meta property=\"og:description\" content=\"\u2713\" \/>\n<meta property=\"og:url\" content=\"https:\/\/envoltaenergia.com\/category\/solar\/\" \/>\n<meta property=\"og:site_name\" content=\"Envolta\" \/>\n<meta property=\"og:image\" content=\"https:\/\/envoltaenergia.com\/wp-content\/uploads\/2023\/07\/AUTOCONSUM-SOLAR-PROCES-EXECUCIO-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"8320\" \/>\n\t<meta property=\"og:image:height\" content=\"5547\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/envoltaenergia.com\\\/category\\\/solar\\\/\",\"url\":\"https:\\\/\\\/envoltaenergia.com\\\/category\\\/solar\\\/\",\"name\":\"Energia Solar archivos - Envolta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/envoltaenergia.com\\\/#website\"},\"description\":\"\u2713\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/envoltaenergia.com\\\/category\\\/solar\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/envoltaenergia.com\\\/category\\\/solar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/envoltaenergia.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Energia Solar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/envoltaenergia.com\\\/#website\",\"url\":\"https:\\\/\\\/envoltaenergia.com\\\/\",\"name\":\"Envolta Energia\",\"description\":\"Consultor\u00eda e ingenier\u00eda en sostenibilidad customizada para empresas\",\"publisher\":{\"@id\":\"https:\\\/\\\/envoltaenergia.com\\\/#organization\"},\"alternateName\":\"Transici\u00f3n a un futuro mejor\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/envoltaenergia.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/envoltaenergia.com\\\/#organization\",\"name\":\"Envolta Energia\",\"url\":\"https:\\\/\\\/envoltaenergia.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/envoltaenergia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/envoltaenergia.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-LOGO.png\",\"contentUrl\":\"https:\\\/\\\/envoltaenergia.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-LOGO.png\",\"width\":1015,\"height\":281,\"caption\":\"Envolta Energia\"},\"image\":{\"@id\":\"https:\\\/\\\/envoltaenergia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Energia Solar archivos - Envolta","description":"\u2713","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Energia Solar archivos - Envolta","og_description":"\u2713","og_url":"https:\/\/envoltaenergia.com\/category\/solar\/","og_site_name":"Envolta","og_image":[{"width":8320,"height":5547,"url":"https:\/\/envoltaenergia.com\/wp-content\/uploads\/2023\/07\/AUTOCONSUM-SOLAR-PROCES-EXECUCIO-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/envoltaenergia.com\/category\/solar\/","url":"https:\/\/envoltaenergia.com\/category\/solar\/","name":"Energia Solar archivos - Envolta","isPartOf":{"@id":"https:\/\/envoltaenergia.com\/#website"},"description":"\u2713","breadcrumb":{"@id":"https:\/\/envoltaenergia.com\/category\/solar\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/envoltaenergia.com\/category\/solar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/envoltaenergia.com\/es\/"},{"@type":"ListItem","position":2,"name":"Energia Solar"}]},{"@type":"WebSite","@id":"https:\/\/envoltaenergia.com\/#website","url":"https:\/\/envoltaenergia.com\/","name":"Envolta Energia","description":"Consultor\u00eda e ingenier\u00eda en sostenibilidad customizada para empresas","publisher":{"@id":"https:\/\/envoltaenergia.com\/#organization"},"alternateName":"Transici\u00f3n a un futuro mejor","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/envoltaenergia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/envoltaenergia.com\/#organization","name":"Envolta Energia","url":"https:\/\/envoltaenergia.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/envoltaenergia.com\/#\/schema\/logo\/image\/","url":"https:\/\/envoltaenergia.com\/wp-content\/uploads\/2023\/02\/cropped-LOGO.png","contentUrl":"https:\/\/envoltaenergia.com\/wp-content\/uploads\/2023\/02\/cropped-LOGO.png","width":1015,"height":281,"caption":"Envolta Energia"},"image":{"@id":"https:\/\/envoltaenergia.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/envoltaenergia.com\/es\/wp-json\/wp\/v2\/categories\/37","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/envoltaenergia.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/envoltaenergia.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/envoltaenergia.com\/es\/wp-json\/wp\/v2\/posts?categories=37"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}